{"id":78,"date":"2026-05-04T11:29:31","date_gmt":"2026-05-04T11:29:31","guid":{"rendered":"https:\/\/mikro.misspellingweb.ch\/index.php\/badezimmer-asbest-2\/"},"modified":"2026-05-05T11:54:53","modified_gmt":"2026-05-05T11:54:53","slug":"mikro","status":"publish","type":"page","link":"https:\/\/mikro.misspellingweb.ch\/","title":{"rendered":"Mikro"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"78\" class=\"elementor elementor-78\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52081fdb e-flex e-con-boxed e-con e-parent\" data-id=\"52081fdb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5176c98a e-con-full e-flex e-con e-child\" data-id=\"5176c98a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-348b8e7e elementor-widget elementor-widget-heading\" data-id=\"348b8e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">mikro<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40437a49 elementor-widget elementor-widget-heading\" data-id=\"40437a49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Ihr Labor f\u00fcr mikroskopische Fragestellungen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d71991d elementor-widget elementor-widget-text-editor\" data-id=\"d71991d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wir untersuchen Partikel, Verunreinigungen und Ablagerungen auf Oberfl\u00e4chen sowie Fremdstoffe und R\u00fcckst\u00e4nde auf ihre m\u00f6gliche Herkunft.<\/p><p>Werkstoffe und Baustoffe k\u00f6nnen auf Ihre chemische Zusammensetzung, auf ihre Homogenit\u00e4t und Qualit\u00e4t untersucht werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b4a6610 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3b4a6610\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">SAS-akkreditiert (Nr. 0595)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00fcr Industrie &amp; Privatpersonen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Partikel ab 1 Mikrometer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4daea376 elementor-widget elementor-widget-button\" data-id=\"4daea376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontakt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kostenlose Anfrage stellen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f4ebea4 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"4f4ebea4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0d0902 e-flex e-con-boxed e-con e-parent\" data-id=\"b0d0902\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8910343 e-con-full e-flex e-con e-child\" data-id=\"8910343\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b84195 elementor-widget elementor-widget-heading\" data-id=\"2b84195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wann kommen Sie zu uns?<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b6b4cb2 elementor-widget elementor-widget-heading\" data-id=\"5b6b4cb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ihr Problem \u2013 unsere Expertise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c9dcf6f elementor-widget elementor-widget-text-editor\" data-id=\"2c9dcf6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Jede Analyse beginnt mit einer konkreten Frage. Wir helfen Ihnen, Antworten zu finden \u2013 pr\u00e4zise, nachvollziehbar und zuverl\u00e4ssig dokumentiert.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-687fc7d elementor-widget elementor-widget-button\" data-id=\"687fc7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontakt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kostenlose Anfrage stellen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38a4948 e-grid e-con-full e-con e-child\" data-id=\"38a4948\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d580b3e e-con-full e-flex e-con e-child\" data-id=\"d580b3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-896154e elementor-widget elementor-widget-heading\" data-id=\"896154e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">01<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf2ea18 elementor-widget elementor-widget-heading\" data-id=\"cf2ea18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Unbekannte Verunreinigungen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-565de2e elementor-widget elementor-widget-text-editor\" data-id=\"565de2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10a2d5b e-con-full e-flex e-con e-child\" data-id=\"10a2d5b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50109a3 elementor-widget elementor-widget-heading\" data-id=\"50109a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">02<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5747a21 elementor-widget elementor-widget-heading\" data-id=\"5747a21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bauteil- oder Werkstoffversagen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8771f6 elementor-widget elementor-widget-text-editor\" data-id=\"a8771f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc0448d e-con-full e-flex e-con e-child\" data-id=\"cc0448d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe1cc72 elementor-widget elementor-widget-heading\" data-id=\"fe1cc72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">03<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2729341 elementor-widget elementor-widget-heading\" data-id=\"2729341\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4tssicherung &amp; Prozessoptimierung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b873a5 elementor-widget elementor-widget-text-editor\" data-id=\"5b873a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ca313b e-con-full e-flex e-con e-child\" data-id=\"8ca313b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2467ad3 elementor-widget elementor-widget-heading\" data-id=\"2467ad3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">04<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba26783 elementor-widget elementor-widget-heading\" data-id=\"ba26783\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Forschung &amp; Entwicklung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9629e8 elementor-widget elementor-widget-text-editor\" data-id=\"d9629e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e310164 e-flex e-con-boxed e-con e-parent\" data-id=\"e310164\" data-element_type=\"container\" data-e-type=\"container\" id=\"morphologie\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2fe3dfc7 e-con-full e-flex e-con e-child\" data-id=\"2fe3dfc7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b206ce6 elementor-widget elementor-widget-heading\" data-id=\"b206ce6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Morphologie<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-529b6ac1 elementor-widget elementor-widget-heading\" data-id=\"529b6ac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Morphologie von Oberfl\u00e4chen und Gef\u00fcgen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1140f52e elementor-widget elementor-widget-text-editor\" data-id=\"1140f52e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Morphologie beschreibt die Form und Gestalt von kleinr\u00e4umigen Bestandteilen oder dem Verbund unterschiedlicher Bestandteile eines heterogen zusammengesetzten Materials. Solche Merkmale erlauben R\u00fcckschl\u00fcsse auf die Identit\u00e4t des Bestandteils oder Materials, seine Herstellung\/Entstehung oder seine Ver\u00e4nderung.<\/p><p>Neben Abmessungen im Bereich von einigen Nanometern bis zu mehreren Millimetern beschreibt die Morphologie \u00fcberwiegend die Ausbildung von Grenzfl\u00e4chen und Oberfl\u00e4chen. Verschiedene Mikroskopieverfahren und unterschiedliche M\u00f6glichkeiten der Abbildung (Detektoren) erzeugen den gew\u00fcnschten Kontrast.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2b0621 elementor-widget elementor-widget-heading\" data-id=\"a2b0621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Alles ausser Fl\u00fcssigkeiten<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d27b15e elementor-widget elementor-widget-text-editor\" data-id=\"d27b15e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Feste Stoffe in Form von Mineralien, keramischen oder metallischen Werkstoffen, Baustoffen sowie Kunststoffe oder biologische Proben lassen sich mikroskopisch charakterisieren. H\u00e4ufig geht es auch um R\u00fcckst\u00e4nde oder Verunreinigungen in industriellen Herstellungsprozessen, beispielsweise von Medikamenten oder Nahrungsmitteln.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11715069 elementor-widget elementor-widget-button\" data-id=\"11715069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontakt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f5c342 e-con-full e-flex e-con e-child\" data-id=\"7f5c342\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d618243 elementor-widget elementor-widget-heading\" data-id=\"d618243\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Beispiele<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25776bc elementor-widget elementor-widget-n-accordion\" data-id=\"25776bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3920\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3920\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Mineralogie <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3920\" class=\"elementor-element elementor-element-584c676 e-con-full e-flex e-con e-child\" data-id=\"584c676\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3920\" class=\"elementor-element elementor-element-263dce1 e-con-full e-flex e-con e-child\" data-id=\"263dce1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74199fb elementor-widget elementor-widget-text-editor\" data-id=\"74199fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Das Quarzkorn l\u00e4sst durch seine Fl\u00e4chen und Kanten die trigonale Kristallstruktur erkennen. Hintergrund: Porenstruktur des Probenahme-Filters mit 0.8 \u00b5 Poren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66766b9 elementor-widget elementor-widget-image\" data-id=\"66766b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/quarz-kristall-angeaezt_191835-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"quarz-kristall-angeaezt_191835 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTMxLCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9xdWFyei1rcmlzdGFsbC1hbmdlYWV6dF8xOTE4MzUtMS5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/quarz-kristall-angeaezt_191835-1.jpg\" class=\"attachment-large size-large wp-image-131\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/quarz-kristall-angeaezt_191835-1.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/quarz-kristall-angeaezt_191835-1-300x225.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/quarz-kristall-angeaezt_191835-1-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3921\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3921\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Aerosol <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3921\" class=\"elementor-element elementor-element-75c6d53 e-con-full e-flex e-con e-child\" data-id=\"75c6d53\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3921\" class=\"elementor-element elementor-element-076c00c e-con-full e-flex e-con e-child\" data-id=\"076c00c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-481c4c6 elementor-widget elementor-widget-text-editor\" data-id=\"481c4c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Oft gibt schon die Form von Partikeln wichtige Hinweise auf eine m\u00f6gliche Herkunft derselben. Die kugeligen Partikel im Bild entstanden beim Eintrocknen von Tr\u00f6pfchen aus L\u00f6sungsmittel und organischem Klebstoff (Haarspray).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83fcb69 elementor-widget elementor-widget-image\" data-id=\"83fcb69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haarspray-bellena_208088.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"haarspray-bellena_208088\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTM1LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9oYWFyc3ByYXktYmVsbGVuYV8yMDgwODguanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haarspray-bellena_208088-1024x768.jpg\" class=\"attachment-large size-large wp-image-135\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haarspray-bellena_208088-1024x768.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haarspray-bellena_208088-300x225.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haarspray-bellena_208088-768x576.jpg 768w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haarspray-bellena_208088.jpg 1190w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3922\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3922\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Aus der Natur <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3922\" class=\"elementor-element elementor-element-5928928 e-con-full e-flex e-con e-child\" data-id=\"5928928\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3922\" class=\"elementor-element elementor-element-75c2995 e-con-full e-flex e-con e-child\" data-id=\"75c2995\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b6cae1 elementor-widget elementor-widget-text-editor\" data-id=\"2b6cae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Nein, das ist kein Corona Virus sondern das Skelett einer Kieselalge aus dem Schlammsammler einer Geb\u00e4ude-Drainage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-880b509 elementor-widget elementor-widget-image\" data-id=\"880b509\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/kieselalgenskelet-in-schlammsammler_213571.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"kieselalgenskelet-in-schlammsammler_213571\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTM2LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9raWVzZWxhbGdlbnNrZWxldC1pbi1zY2hsYW1tc2FtbWxlcl8yMTM1NzEuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/kieselalgenskelet-in-schlammsammler_213571.jpg\" class=\"attachment-large size-large wp-image-136\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/kieselalgenskelet-in-schlammsammler_213571.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/kieselalgenskelet-in-schlammsammler_213571-300x225.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/kieselalgenskelet-in-schlammsammler_213571-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3923\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3923\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Keramik <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3923\" class=\"elementor-element elementor-element-a34c00a e-con-full e-flex e-con e-child\" data-id=\"a34c00a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3923\" class=\"elementor-element elementor-element-9357121 e-con-full e-flex e-con e-child\" data-id=\"9357121\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ebc51c elementor-widget elementor-widget-text-editor\" data-id=\"4ebc51c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Keramische Rohstoffe werden oft mittels Flammensynthese hergestellt. Dabei resultieren kugelige Partikel oder Partikel-Aggregate unterschiedlichster Abmessungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7144335 elementor-widget elementor-widget-image\" data-id=\"7144335\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/keramik-pulver_213306.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"keramik-pulver_213306\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTM3LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9rZXJhbWlrLXB1bHZlcl8yMTMzMDYuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/keramik-pulver_213306.jpg\" class=\"attachment-large size-large wp-image-137\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/keramik-pulver_213306.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/keramik-pulver_213306-300x225.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/keramik-pulver_213306-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3924\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3924\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Staub I <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3924\" class=\"elementor-element elementor-element-97bacc2 e-con-full e-flex e-con e-child\" data-id=\"97bacc2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3924\" class=\"elementor-element elementor-element-d1b48a8 e-con-full e-flex e-con e-child\" data-id=\"d1b48a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1b28d0 elementor-widget elementor-widget-text-editor\" data-id=\"d1b28d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Form und Farbe von Fasern zeigen, dass es sich bei diesem Staub aus einer Wohnung um textile Fasern handelt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baff2cd elementor-widget elementor-widget-image\" data-id=\"baff2cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haus-staub_214214_s1-10x-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"haus-staub_214214_s1-10x (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTM4LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9oYXVzLXN0YXViXzIxNDIxNF9zMS0xMHgtMS5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haus-staub_214214_s1-10x-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-138\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haus-staub_214214_s1-10x-1-1024x768.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haus-staub_214214_s1-10x-1-300x225.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haus-staub_214214_s1-10x-1-768x576.jpg 768w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haus-staub_214214_s1-10x-1.jpg 1187w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3925\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3925\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Staub II <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3925\" class=\"elementor-element elementor-element-9b051c2 e-con-full e-flex e-con e-child\" data-id=\"9b051c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3925\" class=\"elementor-element elementor-element-6f89c70 e-con-full e-flex e-con e-child\" data-id=\"6f89c70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdf469e elementor-widget elementor-widget-text-editor\" data-id=\"bdf469e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<section class=\"section section-lg bg-default\"><div class=\"container\"><div class=\"row row-60\"><div class=\"col-md-6 col-xl-4\"><article class=\"post-minimal\"><div class=\"post-classic-body\"><p>Bei den weissen, durchsichtigen und plattigen Partikeln handel es sich um Hautschuppen. Mittels EDS lassen sich Kohlenstoff, Sauerstoff und wenig Stickstoff erkennen &#8211; die chemische Signatur von Chitin.<\/p><\/div><\/article><\/div><\/div><\/div><\/section><footer class=\"hidden-print\"><div class=\"pre-footer-corporate\"><div class=\"container\"><div class=\"row justify-content-sm-center justify-content-lg-between row-30 row-md-60\"><div class=\"col-sm-10 col-md-4 col-lg-3 col-xl-2\">\u00a0<\/div><\/div><\/div><\/div><\/footer>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-265c755 elementor-widget elementor-widget-image\" data-id=\"265c755\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/hautschuppen-und-fasern-staub-wohnung_195267.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"hautschuppen-und-fasern-staub-wohnung_195267\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTM5LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9oYXV0c2NodXBwZW4tdW5kLWZhc2Vybi1zdGF1Yi13b2hudW5nXzE5NTI2Ny5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/hautschuppen-und-fasern-staub-wohnung_195267-1024x640.jpg\" class=\"attachment-large size-large wp-image-139\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/hautschuppen-und-fasern-staub-wohnung_195267-1024x640.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/hautschuppen-und-fasern-staub-wohnung_195267-300x188.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/hautschuppen-und-fasern-staub-wohnung_195267-768x480.jpg 768w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/hautschuppen-und-fasern-staub-wohnung_195267-1536x960.jpg 1536w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/hautschuppen-und-fasern-staub-wohnung_195267.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Mineralogie\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Das Quarzkorn l\\u00e4sst durch seine Fl\\u00e4chen und Kanten die trigonale Kristallstruktur erkennen. Hintergrund: Porenstruktur des Probenahme-Filters mit 0.8 \\u00b5 Poren.\"}},{\"@type\":\"Question\",\"name\":\"Aerosol\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Oft gibt schon die Form von Partikeln wichtige Hinweise auf eine m\\u00f6gliche Herkunft derselben. Die kugeligen Partikel im Bild entstanden beim Eintrocknen von Tr\\u00f6pfchen aus L\\u00f6sungsmittel und organischem Klebstoff (Haarspray).\"}},{\"@type\":\"Question\",\"name\":\"Aus der Natur\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Nein, das ist kein Corona Virus sondern das Skelett einer Kieselalge aus dem Schlammsammler einer Geb\\u00e4ude-Drainage.\"}},{\"@type\":\"Question\",\"name\":\"Keramik\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Keramische Rohstoffe werden oft mittels Flammensynthese hergestellt. Dabei resultieren kugelige Partikel oder Partikel-Aggregate unterschiedlichster Abmessungen.\"}},{\"@type\":\"Question\",\"name\":\"Staub I\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Form und Farbe von Fasern zeigen, dass es sich bei diesem Staub aus einer Wohnung um textile Fasern handelt.\"}},{\"@type\":\"Question\",\"name\":\"Staub II\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Bei den weissen, durchsichtigen und plattigen Partikeln handel es sich um Hautschuppen. Mittels EDS lassen sich Kohlenstoff, Sauerstoff und wenig Stickstoff erkennen &#8211; die chemische Signatur von Chitin.\\u00a0\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3dc2cd2 e-flex e-con-boxed e-con e-parent\" data-id=\"3dc2cd2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a368624 e-con-full e-flex e-con e-child\" data-id=\"a368624\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc123dd elementor-widget elementor-widget-gallery\" data-id=\"fc123dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haus-staub_214214_s1-10x.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc123dd\" data-elementor-lightbox-title=\"haus-staub_214214_s1-10x\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI5LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9oYXVzLXN0YXViXzIxNDIxNF9zMS0xMHguanBnIiwic2xpZGVzaG93IjoiZmMxMjNkZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/haus-staub_214214_s1-10x-1024x768.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/stahlwolle-02.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc123dd\" data-elementor-lightbox-title=\"stahlwolle-02\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI4LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9zdGFobHdvbGxlLTAyLmpwZyIsInNsaWRlc2hvdyI6ImZjMTIzZGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/stahlwolle-02.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-abrieb-auf-magnethalter_208738.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc123dd\" data-elementor-lightbox-title=\"metall-abrieb-auf-magnethalter_208738\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI3LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9tZXRhbGwtYWJyaWViLWF1Zi1tYWduZXRoYWx0ZXJfMjA4NzM4LmpwZyIsInNsaWRlc2hvdyI6ImZjMTIzZGQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-abrieb-auf-magnethalter_208738-1024x640.jpg\" data-width=\"800\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/21-diatomite-02.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fc123dd\" data-elementor-lightbox-title=\"21-diatomite-02\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI2LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC8yMS1kaWF0b21pdGUtMDIuanBnIiwic2xpZGVzaG93IjoiZmMxMjNkZCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/21-diatomite-02.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab1b385 e-flex e-con-boxed e-con e-parent\" data-id=\"ab1b385\" data-element_type=\"container\" data-e-type=\"container\" id=\"elementanalysen\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-667591a e-con-full e-flex e-con e-child\" data-id=\"667591a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c389f5e elementor-widget elementor-widget-heading\" data-id=\"c389f5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Elementanalysen \u00dcbersicht<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7562038 elementor-widget elementor-widget-heading\" data-id=\"7562038\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Elementanalysen \u2013 der chemische Fingerabdruck<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b041727 elementor-widget elementor-widget-text-editor\" data-id=\"b041727\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Kombination von Raster-Elektronenmikroskopie (REM) und energiedispersiver R\u00f6ntgenspektroskopie (EDS) erlaubt die Bestimmung der chemischen Zusammensetzung von Materialien. Das Interaktionsvolumen von hochenergetischen Elektronen und den Elementen des Feststoffes ist lediglich wenige Kubik-Mikrometer gross.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c982c09 elementor-widget elementor-widget-button\" data-id=\"c982c09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontakt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aca4009 e-grid e-con-full e-con e-child\" data-id=\"aca4009\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fba4dc7 e-con-full e-flex e-con e-child\" data-id=\"fba4dc7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eff70b1 elementor-widget elementor-widget-heading\" data-id=\"eff70b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Elementanalysen<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48abe3f elementor-widget elementor-widget-heading\" data-id=\"48abe3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Chemischer Fingerabdruck<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d055bd9 elementor-widget elementor-widget-text-editor\" data-id=\"d055bd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p>Die Kombination von Morphologie und einer Anzahl sorgf\u00e4ltig ausgew\u00e4hlter Punktanalysen stellt oft ein einfaches Mittel dar zur Charakterisierung inhomogener Materialien.<\/p><p>Durch die Steuerung des Elektronenstrahls im Rasterelektronenmikroskop k\u00f6nnen die Resultate in einem einzigen Analysepunkt oder aber in vielen benachbarten Analysepunkten dargestellt werden. Letzteres erm\u00f6glicht die Erstellung von Elementverteilungsbildern welche die Form und Verteilung von Bereichen mit spezifischen Elementverh\u00e4ltnissen aufzeigen kann.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d1f663 elementor-widget elementor-widget-heading\" data-id=\"4d1f663\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Beispiele<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c3c82 elementor-widget elementor-widget-n-accordion\" data-id=\"b1c3c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1860\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1860\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Abrieb <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1860\" class=\"elementor-element elementor-element-f568acd e-con-full e-flex e-con e-child\" data-id=\"f568acd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1860\" class=\"elementor-element elementor-element-652025c e-con-full e-flex e-con e-child\" data-id=\"652025c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-703c3c0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"703c3c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Produktionsanlagen in der Pharma- und der Lebensmittelindustrie bestehen aus verschiedensten Werkstoffen. Bei mechanischer Einwirkung kann Abrieb entstehen. Die entsprechenden Partikel k\u00f6nnen die Produkte verunreinigen. Abriebpartikel k\u00f6nnen im REM mit EDS auf ihre chemische Zusammensetzung analysiert werden, was \u00fcber die Zuordnung zu Werkstoffen mit \u00e4hnlicher Zusammensetzung zur Ermittlung ihrer Herkunft beitragen kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e266ab elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6e266ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-abrieb-kosmetika_208559.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"metall-abrieb-kosmetika_208559\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU3LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9tZXRhbGwtYWJyaWViLWtvc21ldGlrYV8yMDg1NTkuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-abrieb-kosmetika_208559.jpg\" class=\"attachment-large size-large wp-image-157\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-abrieb-kosmetika_208559.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-abrieb-kosmetika_208559-300x225.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-abrieb-kosmetika_208559-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1861\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1861\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Verunreinigung <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1861\" class=\"elementor-element elementor-element-bc35712 e-con-full e-flex e-con e-child\" data-id=\"bc35712\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1861\" class=\"elementor-element elementor-element-02eec9d e-con-full e-flex e-con e-child\" data-id=\"02eec9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bde2a6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1bde2a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Form, Oberfl\u00e4chenstrukturen und die chemische Zusammensetzung (Energiedispersive R\u00f6ntgenspektroskopie EDX) dieser Partikel zeigen, dass es sich um Sp\u00e4ne aus der Bearbeitung verschiedener nichtrostender St\u00e4hle handelt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3514c9f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"3514c9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-spaene-in-hydraulikoel_211577.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"metall-spaene-in-hydraulikoel_211577\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU4LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9tZXRhbGwtc3BhZW5lLWluLWh5ZHJhdWxpa29lbF8yMTE1NzcuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-spaene-in-hydraulikoel_211577.jpg\" class=\"attachment-large size-large wp-image-158\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-spaene-in-hydraulikoel_211577.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-spaene-in-hydraulikoel_211577-300x225.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/metall-spaene-in-hydraulikoel_211577-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Abrieb\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Produktionsanlagen in der Pharma- und der Lebensmittelindustrie bestehen aus verschiedensten Werkstoffen. Bei mechanischer Einwirkung kann Abrieb entstehen. Die entsprechenden Partikel k\\u00f6nnen die Produkte verunreinigen. Abriebpartikel k\\u00f6nnen im REM mit EDS auf ihre chemische Zusammensetzung analysiert werden, was \\u00fcber die Zuordnung zu Werkstoffen mit \\u00e4hnlicher Zusammensetzung zur Ermittlung ihrer Herkunft beitragen kann.\"}},{\"@type\":\"Question\",\"name\":\"Verunreinigung\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Form, Oberfl\\u00e4chenstrukturen und die chemische Zusammensetzung (Energiedispersive R\\u00f6ntgenspektroskopie EDX) dieser Partikel zeigen, dass es sich um Sp\\u00e4ne aus der Bearbeitung verschiedener nichtrostender St\\u00e4hle handelt.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4283def elementor-widget elementor-widget-gallery\" data-id=\"4283def\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:2,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/21-diatomite-02-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4283def\" data-elementor-lightbox-title=\"21-diatomite-02\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUwLCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC8yMS1kaWF0b21pdGUtMDItMS5qcGciLCJzbGlkZXNob3ciOiI0MjgzZGVmIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/21-diatomite-02-1.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/221-mikrobereichsanalyse.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4283def\" data-elementor-lightbox-title=\"221-mikrobereichsanalyse\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUxLCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC8yMjEtbWlrcm9iZXJlaWNoc2FuYWx5c2UuanBnIiwic2xpZGVzaG93IjoiNDI4M2RlZiJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/221-mikrobereichsanalyse.jpg\" data-width=\"781\" data-height=\"393\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/221-punktanalysen.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4283def\" data-elementor-lightbox-title=\"221-punktanalysen\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUyLCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC8yMjEtcHVua3RhbmFseXNlbi5qcGciLCJzbGlkZXNob3ciOiI0MjgzZGVmIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/221-punktanalysen.jpg\" data-width=\"534\" data-height=\"400\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/222-amalgan.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4283def\" data-elementor-lightbox-title=\"222-amalgan\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUzLCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC8yMjItYW1hbGdhbi5qcGciLCJzbGlkZXNob3ciOiI0MjgzZGVmIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/222-amalgan.jpg\" data-width=\"685\" data-height=\"561\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e64c68c e-con-full e-flex e-con e-child\" data-id=\"e64c68c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54d1f5c elementor-widget elementor-widget-heading\" data-id=\"54d1f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Elementverteilungsbilder<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31ea182 elementor-widget elementor-widget-heading\" data-id=\"31ea182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ortsaufgel\u00f6ste chemische Zusammensetzung\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24f39d5 elementor-widget elementor-widget-text-editor\" data-id=\"24f39d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Wird der Elektronenstrahl w\u00e4hrend der chemischen Analyse \u00fcber die Probenoberfl\u00e4che gerastert, dann k\u00f6nnen sogenannte Elementverteilungsbilder hergestellt werden. Die chemische Information kann ortsaufgel\u00f6st als Elementintensit\u00e4t oder als Phasenzusammensetzung in jedem Punkt dargestellt werden.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61584e2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"61584e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5bad22 elementor-widget elementor-widget-text-editor\" data-id=\"e5bad22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Anhand von Elementintensit\u00e4ten lassen sich leicht unterschiedliche Zusammensetzungen oder chemische Gradienten erfassen.<\/p><p>Punkte mit gleicher oder sehr \u00e4hnlicher Zusammensetzung k\u00f6nnten als Phasen definiert werden.<\/p><p>Die bildliche Darstellung dieser Information erlaubt eine aussagekr\u00e4ftige Charakterisierung von Gef\u00fcgen oder inhomogen zusammengesetzten Feststoffen.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98fd7bc elementor-widget elementor-widget-gallery\" data-id=\"98fd7bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:2,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/elementverteilungsbilder.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"98fd7bc\" data-elementor-lightbox-title=\"elementverteilungsbilder\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY2LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9lbGVtZW50dmVydGVpbHVuZ3NiaWxkZXIuanBnIiwic2xpZGVzaG93IjoiOThmZDdiYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/elementverteilungsbilder.jpg\" data-width=\"766\" data-height=\"596\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/chemische-gradienten.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"98fd7bc\" data-elementor-lightbox-title=\"chemische-gradienten\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY3LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9jaGVtaXNjaGUtZ3JhZGllbnRlbi5qcGciLCJzbGlkZXNob3ciOiI5OGZkN2JjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/chemische-gradienten.jpg\" data-width=\"716\" data-height=\"683\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/222-elementverteilung.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"98fd7bc\" data-elementor-lightbox-title=\"222-elementverteilung\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY4LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC8yMjItZWxlbWVudHZlcnRlaWx1bmcuanBnIiwic2xpZGVzaG93IjoiOThmZDdiYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/222-elementverteilung.jpg\" data-width=\"700\" data-height=\"525\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/chrom-verteilung.jpg_anchorcentermodecropwidth2000height1500rnd132808544830900000.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"98fd7bc\" data-elementor-lightbox-title=\"chrom-verteilung.jpg_anchor=center&amp;mode=crop&amp;width=2000&amp;height=1500&amp;rnd=132808544830900000\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY5LCJ1cmwiOiJodHRwczpcL1wvbWlrcm8ubWlzc3BlbGxpbmd3ZWIuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA1XC9jaHJvbS12ZXJ0ZWlsdW5nLmpwZ19hbmNob3JjZW50ZXJtb2RlY3JvcHdpZHRoMjAwMGhlaWdodDE1MDBybmQxMzI4MDg1NDQ4MzA5MDAwMDAuanBnIiwic2xpZGVzaG93IjoiOThmZDdiYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/chrom-verteilung.jpg_anchorcentermodecropwidth2000height1500rnd132808544830900000-1024x768.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f0dfdc elementor-widget elementor-widget-heading\" data-id=\"5f0dfdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Technische Kenndaten der EDS-Analyse<\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a5d545 e-grid e-con-full e-con e-child\" data-id=\"6a5d545\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f1621a3 e-con-full e-flex e-con e-child\" data-id=\"f1621a3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f79452 elementor-widget elementor-widget-heading\" data-id=\"2f79452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u2265 Be<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb96db elementor-widget elementor-widget-text-editor\" data-id=\"2eb96db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Nachweisbar ab Beryllium (Ordnungszahl 4) \u2013 nahezu das gesamte Periodensystem<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48c81ae e-con-full e-flex e-con e-child\" data-id=\"48c81ae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75c790b elementor-widget elementor-widget-heading\" data-id=\"75c790b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">~1%<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4c3cae elementor-widget elementor-widget-text-editor\" data-id=\"a4c3cae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Nachweisgrenze f\u00fcr einzelne Elemente in Massen-% (je nach Gesamtzusammensetzung)<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f5f705 e-con-full e-flex e-con e-child\" data-id=\"8f5f705\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36188b3 elementor-widget elementor-widget-heading\" data-id=\"36188b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">&lt;10%<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddb7c3b elementor-widget elementor-widget-text-editor\" data-id=\"ddb7c3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><div class=\"section-header\"><p class=\"section-body\">Relativer Fehler der quantitativen Ergebnisse \u2013 robust und reproduzierbar<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a2ed39 e-con-full e-flex e-con e-child\" data-id=\"4a2ed39\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cc62bb elementor-widget elementor-widget-heading\" data-id=\"6cc62bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00b5m\u00b3<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dc3a69 elementor-widget elementor-widget-text-editor\" data-id=\"6dc3a69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Interaktionsvolumen des Elektronenstrahls \u2013 ortsaufl\u00f6sende Mikrobereichsanalyse<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfd7186 e-flex e-con-boxed e-con e-parent\" data-id=\"bfd7186\" data-element_type=\"container\" data-e-type=\"container\" id=\"partikelanalyse\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-324b15b e-con-full e-flex e-con e-child\" data-id=\"324b15b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8620067 elementor-widget elementor-widget-heading\" data-id=\"8620067\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Partikelanalyse<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef33bcf elementor-widget elementor-widget-heading\" data-id=\"ef33bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Automatische Partikelanalyse<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cc4592 elementor-widget elementor-widget-text-editor\" data-id=\"0cc4592\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Statistische Erfassung von Partikelkollektiven anhand von Morphologie und chemischer Zusammensetzung \u2013 f\u00fcr reproduzierbare, skalierbare Ergebnisse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e41860 elementor-widget elementor-widget-heading\" data-id=\"1e41860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wie funktioniert die Partikelanalyse?<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec5f5f3 elementor-widget elementor-widget-text-editor\" data-id=\"ec5f5f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>In der Partikelanalyse werden morphologische Eigenschaften und die chemische Zusammensetzung jedes Partikels automatisch erfasst. Anhand definierter Kriterien werden diese Daten gruppiert und statistisch ausgewertet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae0dfb2 elementor-widget elementor-widget-heading\" data-id=\"ae0dfb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nutzen der Partikelanalyse<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5227ef elementor-widget elementor-widget-text-editor\" data-id=\"a5227ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Bei inhomogenen Korngemischen k\u00f6nnen verschiedene Gruppen von Partikeln erkannt und analytisch ausgewertet werden. Dies erlaubt R\u00fcckschl\u00fcsse \u00fcber die Herkunft einzelner Partikelgruppen. Im Bereich der industriellen Produktion erlaubt die Partikelanalyse die Steuerung der Prozesse und die Optimierung der Produktqualit\u00e4t.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95e9ac3 elementor-widget elementor-widget-button\" data-id=\"95e9ac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontakt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9416b3b e-con-full e-flex e-con e-child\" data-id=\"9416b3b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6664e9 elementor-widget elementor-widget-image\" data-id=\"e6664e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"595\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/partikelanalyse.jpg\" class=\"attachment-large size-large wp-image-171\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/partikelanalyse.jpg 816w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/partikelanalyse-300x223.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/partikelanalyse-768x571.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0c408c e-flex e-con-boxed e-con e-parent\" data-id=\"a0c408c\" data-element_type=\"container\" data-e-type=\"container\" id=\"ratgeber\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5fd49f5 e-con-full e-flex e-con e-child\" data-id=\"5fd49f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cf810d elementor-widget elementor-widget-heading\" data-id=\"6cf810d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ratgeber<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d04fd6 elementor-widget elementor-widget-heading\" data-id=\"8d04fd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Feinstaub in der Wohnung - woran kann es liegen?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14a5bc3 elementor-widget elementor-widget-text-editor\" data-id=\"14a5bc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Innert weniger Tage wurden die Oberfl\u00e4chen auf Ablagen und Einrichtungsgegenst\u00e4nden immer wieder staubig. Die Ursache f\u00fcr diesen Feinstaub wurde lange gesucht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-614a8e3 elementor-widget elementor-widget-button\" data-id=\"614a8e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontakt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3aec4d e-grid e-con-full e-con e-child\" data-id=\"e3aec4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ca6c927 e-con-full e-flex e-con e-child\" data-id=\"ca6c927\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-948e538 elementor-widget elementor-widget-heading\" data-id=\"948e538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ausgangslage<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d927321 elementor-widget elementor-widget-heading\" data-id=\"d927321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hartn\u00e4ckige Staubverunreinigung unbekannter Herkunft<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a61257 elementor-widget elementor-widget-text-editor\" data-id=\"8a61257\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0a5cfb elementor-widget elementor-widget-n-accordion\" data-id=\"a0a5cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1680\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1680\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> 1. Probenahme &amp; REM-Untersuchung <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1680\" class=\"elementor-element elementor-element-f983980 e-con-full e-flex e-con e-child\" data-id=\"f983980\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1680\" class=\"elementor-element elementor-element-a4a4bb8 e-con-full e-flex e-con e-child\" data-id=\"a4a4bb8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5d7a79 elementor-widget elementor-widget-text-editor\" data-id=\"d5d7a79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1681\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1681\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> 2. EDS-Elementanalyse <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1681\" class=\"elementor-element elementor-element-1369d57 e-con-full e-flex e-con e-child\" data-id=\"1369d57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1681\" class=\"elementor-element elementor-element-4331436 e-con-full e-flex e-con e-child\" data-id=\"4331436\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-070ecb4 elementor-widget elementor-widget-text-editor\" data-id=\"070ecb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1682\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1682\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> 3. Vergleichsmessungen &amp; Identifikation <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1682\" class=\"elementor-element elementor-element-c678dc3 e-con-full e-flex e-con e-child\" data-id=\"c678dc3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1682\" class=\"elementor-element elementor-element-0f4017b e-con-full e-flex e-con e-child\" data-id=\"0f4017b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe341a5 elementor-widget elementor-widget-text-editor\" data-id=\"fe341a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1683\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1683\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> 4. Probleml\u00f6sung &amp; Ergebnis <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1683\" class=\"elementor-element elementor-element-37b4c3c e-con-full e-flex e-con e-child\" data-id=\"37b4c3c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1683\" class=\"elementor-element elementor-element-0ec7b19 e-con-full e-flex e-con e-child\" data-id=\"0ec7b19\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d325240 elementor-widget elementor-widget-text-editor\" data-id=\"d325240\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p class=\"section-body\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"1. Probenahme & REM-Untersuchung\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.\"}},{\"@type\":\"Question\",\"name\":\"2. EDS-Elementanalyse\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.\"}},{\"@type\":\"Question\",\"name\":\"3. Vergleichsmessungen & Identifikation\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.\"}},{\"@type\":\"Question\",\"name\":\"4. Probleml\\u00f6sung & Ergebnis\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer ac est ante. Aliquam at ex felis. Integer sed ipsum sem. Pellentesque malesuada tristique ex, vitae elementum tortor pulvinar ut. Praesent non pellentesque nunc, et vestibulum dui. Mauris tincidunt vitae tortor ac vehicula. Suspendisse eget mi ultricies, lobortis nunc in, blandit purus.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a43967 elementor-widget elementor-widget-text-editor\" data-id=\"2a43967\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-header\"><p><strong>Wichtig f\u00fcr eine erfolgreiche Untersuchung:<\/strong>\u00a0Die korrekte Probenahme ist entscheidend. Vor der Entnahme von Proben empfehlen wir unbedingt den vorg\u00e4ngigen Kontakt mit dem Experten \u2013 wir beraten Sie zur geeigneten Vorgehensweise.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5468081 e-con-full e-flex e-con e-child\" data-id=\"5468081\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed2dd19 elementor-widget elementor-widget-image\" data-id=\"ed2dd19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/img_1307.jpg_center0.593045112781954930.55764411027568928modecropwidth2000height1500rnd132808556454100000-1024x768.jpg\" class=\"attachment-large size-large wp-image-184\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/img_1307.jpg_center0.593045112781954930.55764411027568928modecropwidth2000height1500rnd132808556454100000-1024x768.jpg 1024w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/img_1307.jpg_center0.593045112781954930.55764411027568928modecropwidth2000height1500rnd132808556454100000-300x225.jpg 300w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/img_1307.jpg_center0.593045112781954930.55764411027568928modecropwidth2000height1500rnd132808556454100000-768x576.jpg 768w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/img_1307.jpg_center0.593045112781954930.55764411027568928modecropwidth2000height1500rnd132808556454100000-1536x1152.jpg 1536w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/img_1307.jpg_center0.593045112781954930.55764411027568928modecropwidth2000height1500rnd132808556454100000.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44a4def e-flex e-con-boxed e-con e-parent\" data-id=\"44a4def\" data-element_type=\"container\" data-e-type=\"container\" id=\"ueber-uns\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f7ac46c e-con-full e-flex e-con e-child\" data-id=\"f7ac46c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2a1b8e elementor-widget elementor-widget-heading\" data-id=\"a2a1b8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00dcBER UNS<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d5d103 elementor-widget elementor-widget-heading\" data-id=\"1d5d103\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ihre Experten f\u00fcr mikroskopische Untersuchungen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2abeb elementor-widget elementor-widget-button\" data-id=\"df2abeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#kontakt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0be59ee e-con-full e-flex e-con e-child\" data-id=\"0be59ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-431ef20 elementor-widget elementor-widget-text-editor\" data-id=\"431ef20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"s4\">Unser Labor haben wir 2006 in Lenzburg gegr\u00fcndet. Seither ist die Belegschaft stetig gewachsen und wir haben unsere Fachkompetenz im Bereich von Baustoffen, Mikroskopie und Geb\u00e4udeschadstoffen kontinuierlich ausgebaut. Zum 15 j\u00e4hrigen Jubil\u00e4um haben wir die Firma in eine AG umgewandelt. Unsere Erfahrungen und Dienstleistungen stellen wir privaten Bauherren, Handwerkern, Architekten, Planern sowie Geb\u00e4udediagnostikern zur Verf\u00fcgung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1521d93 e-grid e-con-full e-con e-child\" data-id=\"1521d93\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6f98be elementor-widget elementor-widget-image\" data-id=\"c6f98be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/e-logo-swiss-test-labs-01_ohne-text_trans-removebg-preview.png\" class=\"attachment-large size-large wp-image-30\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a818b22 elementor-widget elementor-widget-image\" data-id=\"a818b22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/sas_sts_rgb_595-removebg-preview.png\" class=\"attachment-large size-large wp-image-31\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2443488 elementor-widget elementor-widget-image\" data-id=\"2443488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"31\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/aatest__horizontal_partner_2.png\" class=\"attachment-large size-large wp-image-32\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f7ea1b e-flex e-con-boxed e-con e-parent\" data-id=\"8f7ea1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-27525e4 e-con-full e-flex e-con e-child\" data-id=\"27525e4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ac57d63 e-con-full e-flex e-con e-child\" data-id=\"ac57d63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-048173b elementor-widget elementor-widget-image\" data-id=\"048173b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"525\" src=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/aatest-meik-romer-1.jpg\" class=\"attachment-large size-large wp-image-117\" alt=\"\" srcset=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/aatest-meik-romer-1.jpg 700w, https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/2026\/05\/aatest-meik-romer-1-300x225.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6254d59 e-con-full e-flex e-con e-child\" data-id=\"6254d59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e636ab6 elementor-widget elementor-widget-heading\" data-id=\"e636ab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Initiant und Inhaber<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efb6b7d elementor-widget elementor-widget-heading\" data-id=\"efb6b7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dr. Michael Romer<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6db30c elementor-widget elementor-widget-heading\" data-id=\"f6db30c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00dcber 30 Jahre Berufserfahrung mit Materialtechnologie und Mikroskopie<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4390e41 elementor-widget elementor-widget-text-editor\" data-id=\"4390e41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"s4\">Seit meiner Ausbildung als Naturwissenschaftler an der ETH befasste ich mich mit Mineralogie, Materialtechnologie und Labortechnologie. In meiner langj\u00e4hrigen T\u00e4tigkeit an der Empa und in der Zementindustrie konnte ich meine theoretischen und praktischen Kenntnisse im Bereich der Werkstoffe, Baustoffe und Bautechnologien erweitern. Licht- und Elektronenmikroskopie waren dabei st\u00e4ndige Begleiter. Mehrfach habe ich Pr\u00fcflabore zur Akkreditierung gef\u00fchrt und seit 20 Jahren bin ich als Fachexperte engagiert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6215ae8b e-flex e-con-boxed e-con e-parent\" data-id=\"6215ae8b\" data-element_type=\"container\" data-e-type=\"container\" id=\"reviews\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2422653c e-con-full e-flex e-con e-child\" data-id=\"2422653c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-200c318c elementor-widget elementor-widget-heading\" data-id=\"200c318c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Das sagen Kunden \u00fcber mikro<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a6f13a6 elementor-widget elementor-widget-shortcode\" data-id=\"1a6f13a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"vor %d %s|Heute|Tag|Tagen|Woche|Wochen|Monat|Monaten|Jahr|Jahren\" data-plugin-version=\"13.2.9\" data-layout-id=\"4\" data-layout-category=\"slider\" data-set-id=\"light-background\" data-pid=\"\" data-language=\"de\" data-close-locale=\"Schlie\u00dfen\" data-review-target-width=\"300\" data-css-version=\"2\" data-reply-by-locale=\"Antwort des Eigent\u00fcmers\" data-only-rating-locale=\"Dieser Nutzer hat lediglich eine Bewertung abgegeben.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-3\"> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"N\u00e4chste Bewertung\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Vorherige Bewertung\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1761696000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Gepostet auf Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLg9SKXqrDZ0VDebZOFvLBxT3OQ66mY_IOkXWkN4etG0wf3ow=w40-h40-c-rp-mo-br100\" alt=\"Sonja-Christina Lorenz profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Sonja-Christina Lorenz <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex \u00fcberpr\u00fcft, ob die Originalquelle der Bewertung Google ist.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Herzlichen Dank an Herrn Romer und sein Team f\u00fcr die kompetente, zuverl\u00e4ssige und unterst\u00fctzende Betreuung. Fragen werden freundlich und verst\u00e4ndlich beantwortet \u2013 sehr empfehlenswert!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ausblenden\" data-open-text=\"Weiterlesen\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1736553600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Gepostet auf Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKrzWfpIsCDNumWhLnAML1Hi-vlLq7oIJWtHbMmjgtel7_g3Q=w40-h40-c-rp-mo-br100\" alt=\"Moritz Zenker profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Moritz Zenker <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex \u00fcberpr\u00fcft, ob die Originalquelle der Bewertung Google ist.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Herr Romer und sein Team sind \u00e4usserst zuverl\u00e4ssig und beantworten gerne Fragen! Grade bei diesem Thema ist es gut sich sicher aufgehoben zu f\u00fchlen.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ausblenden\" data-open-text=\"Weiterlesen\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1730419200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Gepostet auf Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKdN1ehrjwD61MYsoRVinyj47xfZlKNuKJQLgoikBmOtkGfpQ=w40-h40-c-rp-mo-br100\" alt=\"Maja Wipr\u00e4chtiger profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Maja Wipr\u00e4chtiger <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex \u00fcberpr\u00fcft, ob die Originalquelle der Bewertung Google ist.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Herr Romer konnte uns extrem schnell und kompetent unterst\u00fctzen. Herzlichen Dank daf\u00fcr!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ausblenden\" data-open-text=\"Weiterlesen\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1730332800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Gepostet auf Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLNyWwISRkqWmCqoMGs3gMa_sDu9BVWOFIdAm51rkP37A0HjA=w40-h40-c-rp-mo-br100\" alt=\"Ramona Gautschi profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Ramona Gautschi <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex \u00fcberpr\u00fcft, ob die Originalquelle der Bewertung Google ist.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->\u00c4usserst kompetente und unkomplizierte Beratung, 100%ige Weiterempfehlung. :)<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ausblenden\" data-open-text=\"Weiterlesen\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1725148800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Gepostet auf Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVdiURCAjDV_RbPErhG439uXy7FK1m_3mwkq6OXBFTYjqy1pW4i=w40-h40-c-rp-mo-br100\" alt=\"Jonas Huber profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jonas Huber <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex \u00fcberpr\u00fcft, ob die Originalquelle der Bewertung Google ist.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Herr Romer und sein Team  von der Aatest haben meine diversen Zusatzfragen zu einer Asbestanalyse sehr professionell, geduldig und mit grossem Fachwissen beantwortet. Der pers\u00f6nliche Kontakt und die Freundlichkeit sind top -- vielen Dank!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ausblenden\" data-open-text=\"Weiterlesen\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1719619200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Gepostet auf Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXMu4Z9rWCca3vNhrsDupuVtmiqUbRYJlNRewecmXk9gheXWS4Y=w40-h40-c-rp-mo-ba5-br100\" alt=\"Yuri L. profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Yuri L. <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex \u00fcberpr\u00fcft, ob die Originalquelle der Bewertung Google ist.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Seit ich diese Firma auf Google entdeckt habe sende ich alle meine Asbestproben dahin. Ich bin \u00e4usserst zufrieden mit der Aatest AG. Die Formulare sind sehr \u00fcbersichtlich und die Asbestproben hat man meistens bereits nach 3 Arbeitstagen, mit dem Expresswunsch bereits nach 1 Arbeitstag.\nAuch wurde ich bereits telefonisch dar\u00fcber informiert dass Materialien die ich eingeschickt habe vermutlich kein Asbest enthalten, ob sie diese trotzdem testen sollen.\nDie Ehrlichkeit und Freundlichkeit dieser Firma sch\u00e4tzte ich sehr und darum werde ich weiterhin alle meine Asbestproben dieser Firma anvertrauen.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ausblenden\" data-open-text=\"Weiterlesen\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1695859200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Gepostet auf Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWp6H1qXF9PFyD1_bJIEuAaJZ9QjXayMzVmrIlslTQvvKFRECPZ=w40-h40-c-rp-mo-ba4-br100\" alt=\"evolution social club profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> evolution social club <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex \u00fcberpr\u00fcft, ob die Originalquelle der Bewertung Google ist.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Este lugar es un lugar para hacer pruebas de amiento y otros contaminantes<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ausblenden\" data-open-text=\"Weiterlesen\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1692748800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Gepostet auf Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKT0Cp3ZEjfANFNyLt4USM1h8AXMZFaQNED0jMR4oJGQh_19A=w40-h40-c-rp-mo-br100\" alt=\"Isaias Haller profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Isaias Haller <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex \u00fcberpr\u00fcft, ob die Originalquelle der Bewertung Google ist.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Gestern Abend habe ich die Aatest AG \u00fcber deren Website kontaktiert, weil ich mir nicht sicher war, ob ein alter Teich im Garten mit Asbest gebaut wurde.\nHeute haben sie mich telefonisch kontaktiert, mich beraten und anhand der Bilder, die ich ihnen per Whatsapp geschickt habe, konnten sie mir best\u00e4tigen, dass in den Baumaterialien kein Asbest enthalten ist.\nIch bin einfach begeistert von der Professionalit\u00e4t und dem Service, den sie mir geboten haben.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ausblenden\" data-open-text=\"Weiterlesen\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <\/div>    <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/mikro.misspellingweb.ch\/wp-content\/uploads\/trustindex-google-widget.css?1777897123\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51b8a01 e-flex e-con-boxed e-con e-parent\" data-id=\"51b8a01\" data-element_type=\"container\" data-e-type=\"container\" id=\"faq\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3e92cca1 e-con-full e-flex e-con e-child\" data-id=\"3e92cca1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59846108 elementor-widget elementor-widget-heading\" data-id=\"59846108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">FAQ \u2013 mikro<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54157c2 elementor-widget elementor-widget-n-accordion\" data-id=\"54157c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8810\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8810\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Was ist vor dem Umbau zu tun? <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8810\" class=\"elementor-element elementor-element-2a9cc00b e-con-full e-flex e-con e-child\" data-id=\"2a9cc00b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8810\" class=\"elementor-element elementor-element-7950d60c e-con-full e-flex e-con e-child\" data-id=\"7950d60c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-157a9ce elementor-widget elementor-widget-text-editor\" data-id=\"157a9ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Zum Schutz der Gesundheit von Handwerkern und Bewohnern muss vorg\u00e4ngig abgekl\u00e4rt werden, ob Schadstoffe im Spiel sind. Das ist nicht nur vern\u00fcnftig, sondern auch eine Forderung des Abfallgesetztes.<\/p><p class=\"p1\">Falls Schadstoffe vorliegen, m\u00fcssen die entsprechenden Baustoffe nach den Vorgaben der SUVA fachgerecht entfernt und gem\u00e4ss dem Abfallgesetzt richtig entsorgt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8811\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8811\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Welche Baustoffe k\u00f6nnen Schadstoffe enthalten? <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8811\" class=\"elementor-element elementor-element-102777aa e-con-full e-flex e-con e-child\" data-id=\"102777aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8811\" class=\"elementor-element elementor-element-5278333c e-con-full e-flex e-con e-child\" data-id=\"5278333c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-781864fa elementor-widget elementor-widget-text-editor\" data-id=\"781864fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Die folgende Auflistung gibt einen kurzen \u00dcberblick \u00fcber die h\u00e4ufig vorliegenden Baustoffe mit Verdacht auf Schadstoffe in einem Badezimmer. Diese \u00dcbersicht erhebt keinen Anspruch auf Vollst\u00e4ndigkeit.<\/p><ul class=\"ul1\"><li class=\"li1\">Wandfliesen (Fliesenkleber)<\/li><li class=\"li1\">Bodenfliesen (Fliesenkleber)<\/li><li class=\"li1\">Sockelplatten (Fliesenkleber)<\/li><li class=\"li1\">Quadratische Kunststoff-Platten am Boden und\/oder ihr Klebstoff<\/li><li class=\"li1\">Grossformatige Kunststoffbel\u00e4ge an Wand und\/oder Boden<\/li><li class=\"li1\">Putz, Abrieb oder Tapeten an der Wand und\/oder der Decke<\/li><li class=\"li1\">Fenster (Anschlagkitt und\/oder Glaserkitt)<\/li><\/ul><p class=\"p1\">Die vollst\u00e4ndige Liste der schadstoff-verd\u00e4chtigen Baustoffe ist auf <a href=\"https:\/\/polludoc.ch\/de\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">Polludoc<\/span><\/a> publiziert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8812\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8812\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Wer kann Proben f\u00fcr die Pr\u00fcfung im Labor entnehmen? <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8812\" class=\"elementor-element elementor-element-6070fef3 e-con-full e-flex e-con e-child\" data-id=\"6070fef3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8812\" class=\"elementor-element elementor-element-70b84c41 e-con-full e-flex e-con e-child\" data-id=\"70b84c41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3717a99f elementor-widget elementor-widget-text-editor\" data-id=\"3717a99f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Sie k\u00f6nnen selbst Proben entnehmen, ben\u00f6tigen dazu aber Werkzeuge und geeignetes Verpackungsmaterial f\u00fcr die Proben. Sie k\u00f6nnen auch einen Handwerker \u2013 beispielsweise Ihren Plattenleger \u2013 beauftragen, die Proben f\u00fcr Sie zu entnehmen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8813\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8813\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Wie kann ich selbst Proben von Baustoffen entnehmen? <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8813\" class=\"elementor-element elementor-element-d366360 e-con-full e-flex e-con e-child\" data-id=\"d366360\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8813\" class=\"elementor-element elementor-element-43629c73 e-con-full e-flex e-con e-child\" data-id=\"43629c73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-543b8a5e elementor-widget elementor-widget-text-editor\" data-id=\"543b8a5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Die g\u00e4ngigen M\u00f6glichkeiten mit geeigneten Werkzeugen oder einem Probenahme Kit werden auf <span style=\"text-decoration: underline;\"><a href=\"https:\/\/app.sos-asbestos.ch\/sample\/how-to\/?lang=de\" target=\"_blank\" rel=\"noopener\">SOS-Asbest<\/a><\/span> vorgestellt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8814\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8814\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h4 class=\"e-n-accordion-item-title-text\"> Wann brauche ich einen Experten f\u00fcr Geb\u00e4udeschadstoffe? <\/h4><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8814\" class=\"elementor-element elementor-element-2fb3f6dd e-con-full e-flex e-con e-child\" data-id=\"2fb3f6dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8814\" class=\"elementor-element elementor-element-2aaf2056 e-con-full e-flex e-con e-child\" data-id=\"2aaf2056\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c80e8b1 elementor-widget elementor-widget-text-editor\" data-id=\"c80e8b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Wenn Ihr Umbauprojekt etwas komplexer ist und mehrere R\u00e4ume und Nasszellen betroffen sind, dann wird allgemein empfohlen eine Fachperson (Bauschadstoff-Diagnostiker) beizuziehen. \u00dcber unsere Homepage <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.sos-asbestos.ch\/de\/wie-schutzt-man-sich-vor-asbest\/\" target=\"_blank\" rel=\"noopener\">SOS-Asbest<\/a><\/span> k\u00f6nnen Sie sich mit einem Diagnostiker vermitteln lassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Was ist vor dem Umbau zu tun?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Zum Schutz der Gesundheit von Handwerkern und Bewohnern muss vorg\\u00e4ngig abgekl\\u00e4rt werden, ob Schadstoffe im Spiel sind. Das ist nicht nur vern\\u00fcnftig, sondern auch eine Forderung des Abfallgesetztes.Falls Schadstoffe vorliegen, m\\u00fcssen die entsprechenden Baustoffe nach den Vorgaben der SUVA fachgerecht entfernt und gem\\u00e4ss dem Abfallgesetzt richtig entsorgt werden.\"}},{\"@type\":\"Question\",\"name\":\"Welche Baustoffe k\\u00f6nnen Schadstoffe enthalten?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Die folgende Auflistung gibt einen kurzen \\u00dcberblick \\u00fcber die h\\u00e4ufig vorliegenden Baustoffe mit Verdacht auf Schadstoffe in einem Badezimmer. Diese \\u00dcbersicht erhebt keinen Anspruch auf Vollst\\u00e4ndigkeit.Wandfliesen (Fliesenkleber)Bodenfliesen (Fliesenkleber)Sockelplatten (Fliesenkleber)Quadratische Kunststoff-Platten am Boden und\\\/oder ihr KlebstoffGrossformatige Kunststoffbel\\u00e4ge an Wand und\\\/oder BodenPutz, Abrieb oder Tapeten an der Wand und\\\/oder der DeckeFenster (Anschlagkitt und\\\/oder Glaserkitt)Die vollst\\u00e4ndige Liste der schadstoff-verd\\u00e4chtigen Baustoffe ist auf Polludoc publiziert.\"}},{\"@type\":\"Question\",\"name\":\"Wer kann Proben f\\u00fcr die Pr\\u00fcfung im Labor entnehmen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Sie k\\u00f6nnen selbst Proben entnehmen, ben\\u00f6tigen dazu aber Werkzeuge und geeignetes Verpackungsmaterial f\\u00fcr die Proben. Sie k\\u00f6nnen auch einen Handwerker \\u2013 beispielsweise Ihren Plattenleger \\u2013 beauftragen, die Proben f\\u00fcr Sie zu entnehmen.\"}},{\"@type\":\"Question\",\"name\":\"Wie kann ich selbst Proben von Baustoffen entnehmen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Die g\\u00e4ngigen M\\u00f6glichkeiten mit geeigneten Werkzeugen oder einem Probenahme Kit werden auf SOS-Asbest vorgestellt.\"}},{\"@type\":\"Question\",\"name\":\"Wann brauche ich einen Experten f\\u00fcr Geb\\u00e4udeschadstoffe?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Wenn Ihr Umbauprojekt etwas komplexer ist und mehrere R\\u00e4ume und Nasszellen betroffen sind, dann wird allgemein empfohlen eine Fachperson (Bauschadstoff-Diagnostiker) beizuziehen. \\u00dcber unsere Homepage SOS-Asbest k\\u00f6nnen Sie sich mit einem Diagnostiker vermitteln lassen.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6eaf779b e-con-full e-flex e-con e-parent\" data-id=\"6eaf779b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6a1252fd e-con-full e-flex e-con e-child\" data-id=\"6a1252fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3526b9f8 elementor-widget elementor-widget-heading\" data-id=\"3526b9f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">mikro Experten<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4599fe7a elementor-widget elementor-widget-heading\" data-id=\"4599fe7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Kontaktieren Sie uns <\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72b2da3 e-con-full e-flex e-con e-child\" data-id=\"72b2da3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a654b49 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2a654b49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-pin\" viewBox=\"0 0 288 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M112 316.94v156.69l22.02 33.02c4.75 7.12 15.22 7.12 19.97 0L176 473.63V316.94c-10.39 1.92-21.06 3.06-32 3.06s-21.61-1.14-32-3.06zM144 0C64.47 0 0 64.47 0 144s64.47 144 144 144 144-64.47 144-144S223.53 0 144 0zm0 76c-37.5 0-68 30.5-68 68 0 6.62-5.38 12-12 12s-12-5.38-12-12c0-50.73 41.28-92 92-92 6.62 0 12 5.38 12 12s-5.38 12-12 12z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAdresse\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tc\/o Aatest AG<\/br>\nNiederlenzer Kirchweg 1<br>\nCH - 5600 Lenzburg\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90c9b08 e-con-full e-flex e-con e-child\" data-id=\"90c9b08\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cfbfad0 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3cfbfad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tHauptnummer\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"tel:+41 62 891 33 61;\">+41 62 891 33 61<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2af40de4 e-con-full e-flex e-con e-child\" data-id=\"2af40de4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9669106 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9669106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"mailto:aatest@aatest.ch;\">aatest@aatest.ch<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3421bfa0 e-con-full e-flex e-con e-child\" data-id=\"3421bfa0\" data-element_type=\"container\" data-e-type=\"container\" id=\"kontakt\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fd6e90e elementor-widget elementor-widget-heading\" data-id=\"5fd6e90e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ihre Anfrage<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a58b1 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"2a58b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;N\\u00e4chster&quot;,&quot;step_previous_label&quot;:&quot;Voriger&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Badezimmer Formular\" aria-label=\"Badezimmer Formular\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"78\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"2a58b1\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"78\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_154dcc0 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_154dcc0\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefonnummer\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_154dcc0]\" id=\"form-field-field_154dcc0\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNachricht\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_b5341a2 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_b5341a2\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>mikro Ihr Labor f\u00fcr mikroskopische Fragestellungen Wir untersuchen Partikel, Verunreinigungen und Ablagerungen auf Oberfl\u00e4chen sowie Fremdstoffe und R\u00fcckst\u00e4nde auf ihre m\u00f6gliche Herkunft. Werkstoffe und Baustoffe k\u00f6nnen auf Ihre chemische Zusammensetzung, auf ihre Homogenit\u00e4t und Qualit\u00e4t untersucht werden. SAS-akkreditiert (Nr. 0595) F\u00fcr Industrie &amp; Privatpersonen Partikel ab 1 Mikrometer Kostenlose Anfrage stellen Wann kommen Sie zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-78","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mikro.misspellingweb.ch\/index.php\/wp-json\/wp\/v2\/pages\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikro.misspellingweb.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mikro.misspellingweb.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mikro.misspellingweb.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mikro.misspellingweb.ch\/index.php\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":65,"href":"https:\/\/mikro.misspellingweb.ch\/index.php\/wp-json\/wp\/v2\/pages\/78\/revisions"}],"predecessor-version":[{"id":210,"href":"https:\/\/mikro.misspellingweb.ch\/index.php\/wp-json\/wp\/v2\/pages\/78\/revisions\/210"}],"wp:attachment":[{"href":"https:\/\/mikro.misspellingweb.ch\/index.php\/wp-json\/wp\/v2\/media?parent=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}